{"id":9900,"date":"2026-07-14T11:52:11","date_gmt":"2026-07-14T08:52:11","guid":{"rendered":"https:\/\/zanae.gr\/news\/zanae-at-gulfood-2026\/"},"modified":"2026-07-14T13:58:27","modified_gmt":"2026-07-14T10:58:27","slug":"zanae-at-gulfood-2026","status":"publish","type":"post","link":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/","title":{"rendered":"ZANAE at Gulfood 2026"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 100% + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>ZANAE participated in Gulfood 2026, reaffirming its strong presence in the international food market.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 100% + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"\u0397 ZANAE \u03c3\u03c4\u03b7\u03bd Gulfood 2026\" src=\"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\" alt class=\"img-responsive wp-image-9876\" srcset=\"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026-200x200.webp 200w, https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026-400x400.webp 400w, https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026-600x600.webp 600w, https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026-800x800.webp 800w, https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp 1080w\" sizes=\"(max-width: 640px) 100vw, 1080px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p>During the exhibition, the company showcased its product portfolio and authentic Mediterranean flavors to professionals from around the world, while its booth served as a key meeting point for networking with representatives of the global food industry.<\/p>\n<p>Its participation contributed to further strengthening its export activity and exploring new business opportunities.<\/p>\n<p>ZANAE\u2019s presence at Gulfood 2026 concluded with a positive outcome, enhancing its international image and confirming its strategy of continuous growth and extroversion.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":9876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-9900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZANAE at Gulfood 2026 - Zanae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZANAE at Gulfood 2026 - Zanae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.zanae.gr\/?locale=el_GR\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T08:52:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T10:58:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"zanae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"zanae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/\"},\"author\":{\"name\":\"zanae\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/#\\\/schema\\\/person\\\/1de7742dda394909ece7e3cacacfa1ee\"},\"headline\":\"ZANAE at Gulfood 2026\",\"datePublished\":\"2026-07-14T08:52:11+00:00\",\"dateModified\":\"2026-07-14T10:58:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/\"},\"wordCount\":3037,\"image\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zanae.gr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\",\"articleSection\":[\"Our news\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/\",\"url\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/\",\"name\":\"ZANAE at Gulfood 2026 - Zanae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zanae.gr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\",\"datePublished\":\"2026-07-14T08:52:11+00:00\",\"dateModified\":\"2026-07-14T10:58:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/#\\\/schema\\\/person\\\/1de7742dda394909ece7e3cacacfa1ee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zanae.gr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\",\"contentUrl\":\"https:\\\/\\\/zanae.gr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/news\\\/zanae-at-gulfood-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/zanae.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZANAE at Gulfood 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zanae.gr\\\/en\\\/\",\"name\":\"Zanae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zanae.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zanae.gr\\\/en\\\/#\\\/schema\\\/person\\\/1de7742dda394909ece7e3cacacfa1ee\",\"name\":\"zanae\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZANAE at Gulfood 2026 - Zanae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/","og_locale":"en_US","og_type":"article","og_title":"ZANAE at Gulfood 2026 - Zanae","og_url":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/","og_site_name":"Zanae","article_publisher":"https:\/\/www.facebook.com\/www.zanae.gr\/?locale=el_GR","article_published_time":"2026-07-14T08:52:11+00:00","article_modified_time":"2026-07-14T10:58:27+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp","type":"image\/webp"}],"author":"zanae","twitter_card":"summary_large_image","twitter_misc":{"Written by":"zanae","Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#article","isPartOf":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/"},"author":{"name":"zanae","@id":"https:\/\/zanae.gr\/en\/#\/schema\/person\/1de7742dda394909ece7e3cacacfa1ee"},"headline":"ZANAE at Gulfood 2026","datePublished":"2026-07-14T08:52:11+00:00","dateModified":"2026-07-14T10:58:27+00:00","mainEntityOfPage":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/"},"wordCount":3037,"image":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp","articleSection":["Our news"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/","url":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/","name":"ZANAE at Gulfood 2026 - Zanae","isPartOf":{"@id":"https:\/\/zanae.gr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#primaryimage"},"image":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp","datePublished":"2026-07-14T08:52:11+00:00","dateModified":"2026-07-14T10:58:27+00:00","author":{"@id":"https:\/\/zanae.gr\/en\/#\/schema\/person\/1de7742dda394909ece7e3cacacfa1ee"},"breadcrumb":{"@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#primaryimage","url":"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp","contentUrl":"https:\/\/zanae.gr\/wp-content\/uploads\/2026\/07\/\u0397-ZANAE-\u03c3\u03c4\u03b7\u03bd-Gulfood-2026.webp","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/zanae.gr\/en\/news\/zanae-at-gulfood-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/zanae.gr\/en\/"},{"@type":"ListItem","position":2,"name":"ZANAE at Gulfood 2026"}]},{"@type":"WebSite","@id":"https:\/\/zanae.gr\/en\/#website","url":"https:\/\/zanae.gr\/en\/","name":"Zanae","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zanae.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/zanae.gr\/en\/#\/schema\/person\/1de7742dda394909ece7e3cacacfa1ee","name":"zanae"}]}},"_links":{"self":[{"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/posts\/9900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/comments?post=9900"}],"version-history":[{"count":3,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/posts\/9900\/revisions"}],"predecessor-version":[{"id":9903,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/posts\/9900\/revisions\/9903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/media\/9876"}],"wp:attachment":[{"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/media?parent=9900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/categories?post=9900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zanae.gr\/en\/wp-json\/wp\/v2\/tags?post=9900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}